{"id":217499,"date":"2025-09-02T12:00:50","date_gmt":"2025-09-02T12:00:50","guid":{"rendered":"https:\/\/homeofwool.com\/?post_type=product&#038;p=217499"},"modified":"2026-02-09T10:24:44","modified_gmt":"2026-02-09T10:24:44","slug":"coperta-termica-nomad","status":"publish","type":"product","link":"https:\/\/homeofwool.com\/it\/shop\/nomad-heat-blanket\/","title":{"rendered":"Coperta pesante in lana"},"content":{"rendered":"<p>Questa coperta da campeggio unisce l'artigianato antico al comfort moderno. Realizzata in lana naturale 100%, offre un perfetto equilibrio tra calore e traspirabilit\u00e0.<\/p>\n<p>Le propriet\u00e0 termoregolatrici della lana aiutano il corpo a mantenere un livello di calore confortevole senza surriscaldarsi. Grazie alla naturale resistenza della lana agli acari della polvere e ai batteri, questa \u00e8 una coperta realmente ipoallergenica. Sicura, pulita e confortevole. Adatta a chi soffre di sensibilit\u00e0 e in grado di offrire un comfort puro in cui potersi davvero rilassare.<\/p>\n<p>Tutti i nostri prodotti sono privi di sostanze chimiche. Che venga utilizzata come coperta da campeggio, da glamping o da esterno, questa coperta in lana offre un comfort autentico e un senso di vicinanza alla natura. Realizziamo ogni coperta in Bulgaria per la nostra collezione Nomad Heat. \u00c8 progettata per i viaggi e l'uso quotidiano. \u00c8 calda e resistente. Realizzata per durare di generazione in generazione.<\/p>\n<p><strong>OPZIONI DI DIMENSIONE:<\/strong><\/p>\n<ul>\n<li>63 x 75\u2033 (160 \u0445 190 cm)<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Avvolgiti nel comfort della nostra pesante coperta di lana. Tessuta con fibre di pura lana, ha l'aspetto autentico e la bellezza dei colori naturali della lana. Termoregolante e traspirante, offre il peso rassicurante di un abbraccio rassicurante. Ti mantiene caldo e comodo, ma mai sudato o soffocante. Nessun colorante o sostanza chimica. Solo fibre di pura lana che trasformano le fredde giornate e notti in momenti di comfort.<\/p>\n<div class=\"global-icon-set\">\n<div class=\"global-icon-set__items\">\n<div class=\"global-icon-set__item\">\n<div class=\"global-icon-set__image\">\n                                    <img decoding=\"async\" src=\"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/handmade-icon-300x300.png\" alt=\"icona fatta a mano\" \/>\n                                <\/div>\n<div class=\"global-icon-set__title\">Fatto a mano<\/div>\n<\/p><\/div>\n<div class=\"global-icon-set__item\">\n<div class=\"global-icon-set__image\">\n                                    <img decoding=\"async\" src=\"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/VOCs-min-300x300.png\" alt=\"voci libere\" \/>\n                                <\/div>\n<div class=\"global-icon-set__title\">Senza COV<\/div>\n<\/p><\/div>\n<div class=\"global-icon-set__item\">\n<div class=\"global-icon-set__image\">\n                                    <img decoding=\"async\" src=\"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/FR-min-300x300.png\" alt=\"icona resistente al fuoco\" \/>\n                                <\/div>\n<div class=\"global-icon-set__title\">Resistente alla fiamma<\/div>\n<\/p><\/div>\n<div class=\"global-icon-set__item\">\n<div class=\"global-icon-set__image\">\n                                    <img decoding=\"async\" src=\"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/Hypoallergenic-min-300x300.png\" alt=\"icona ipoallergenica\" \/>\n                                <\/div>\n<div class=\"global-icon-set__title\">Ipoallergenico<\/div>\n<\/p><\/div>\n<div class=\"global-icon-set__item\">\n<div class=\"global-icon-set__image\">\n                                    <img decoding=\"async\" src=\"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/free-of-synthetics-icon-300x300.png\" alt=\"icona priva di sostanze sintetiche\" \/>\n                                <\/div>\n<div class=\"global-icon-set__title\">Privo di sostanze sintetiche<\/div>\n<\/p><\/div>\n<div class=\"global-icon-set__item\">\n<div class=\"global-icon-set__image\">\n                                    <img decoding=\"async\" src=\"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/chemical-free-icon-300x300.png\" alt=\"icona senza sostanze chimiche\" \/>\n                                <\/div>\n<div class=\"global-icon-set__title\">Senza sostanze chimiche<\/div>\n<\/p><\/div>\n<div class=\"global-icon-set__item\">\n<div class=\"global-icon-set__image\">\n                                    <img decoding=\"async\" src=\"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/certified-materials-icon-300x300.png\" alt=\"icona dei materiali certificati\" \/>\n                                <\/div>\n<div class=\"global-icon-set__title\">100% Materiali puri certificati<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>","protected":false},"featured_media":228005,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1366,60],"product_tag":[61,62,63,64,65,66,67,68,69,70,71],"class_list":{"0":"post-217499","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-womens-day","7":"product_cat-blankets-duvets","8":"product_tag-all-natural-wool-blankets","9":"product_tag-chemical-free-wool-blanket","10":"product_tag-handmade-blanket","11":"product_tag-heavyweight-wool-blanket","12":"product_tag-large-wool-blanket","13":"product_tag-organic-wool-blanket","14":"product_tag-pure-wool-blanket","15":"product_tag-throws-for-beds","16":"product_tag-travel-blanket","17":"product_tag-washable-wool-blanket","18":"product_tag-wool-blanket-camping","20":"first","21":"instock","22":"shipping-taxable","23":"purchasable","24":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Heavy Wool Blanket \u2013 Organic, Hypoallergenic Throw for Beds | Home of Wool<\/title>\n<meta name=\"description\" content=\"Durable and natural, the Heavy Wool Blanket provides breathable warmth. Hypoallergenic and toxin-free, it ensures sustainable comfort for outdoor adventures, glamping, or cozy nights.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homeofwool.com\/it\/negozio\/coperta-termica-nomad\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heavy Wool Blanket\" \/>\n<meta property=\"og:description\" content=\"Durable and natural, the Heavy Wool Blanket provides breathable warmth. Hypoallergenic and toxin-free, it ensures sustainable comfort for outdoor adventures, glamping, or cozy nights.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homeofwool.com\/it\/negozio\/coperta-termica-nomad\/\" \/>\n<meta property=\"og:site_name\" content=\"Home of Wool\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/HomeOfWoolOfficial\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T10:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/home-of-wool-nomad-heavy-wool-blanket-mainn.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/homeofwool.com\\\/shop\\\/nomad-heat-blanket\\\/\",\"url\":\"https:\\\/\\\/homeofwool.com\\\/shop\\\/nomad-heat-blanket\\\/\",\"name\":\"Heavy Wool Blanket \u2013 Organic, Hypoallergenic Throw for Beds | Home of Wool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homeofwool.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/homeofwool.com\\\/shop\\\/nomad-heat-blanket\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/homeofwool.com\\\/shop\\\/nomad-heat-blanket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/homeofwool.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/home-of-wool-nomad-heavy-wool-blanket-mainn.jpg\",\"datePublished\":\"2025-09-02T12:00:50+00:00\",\"dateModified\":\"2026-02-09T10:24:44+00:00\",\"description\":\"Durable and natural, the Heavy Wool Blanket provides breathable warmth. Hypoallergenic and toxin-free, it ensures sustainable comfort for outdoor adventures, glamping, or cozy nights.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homeofwool.com\\\/shop\\\/nomad-heat-blanket\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/homeofwool.com\\\/shop\\\/nomad-heat-blanket\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/homeofwool.com\\\/shop\\\/nomad-heat-blanket\\\/#primaryimage\",\"url\":\"https:\\\/\\\/homeofwool.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/home-of-wool-nomad-heavy-wool-blanket-mainn.jpg\",\"contentUrl\":\"https:\\\/\\\/homeofwool.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/home-of-wool-nomad-heavy-wool-blanket-mainn.jpg\",\"width\":1920,\"height\":1536,\"caption\":\"nomad heat folded heavy wool blanket\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homeofwool.com\\\/shop\\\/nomad-heat-blanket\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/homeofwool.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"shop\",\"item\":\"https:\\\/\\\/homeofwool.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Heavy Wool Blanket\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homeofwool.com\\\/#website\",\"url\":\"https:\\\/\\\/homeofwool.com\\\/\",\"name\":\"Home of Wool\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/homeofwool.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homeofwool.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/homeofwool.com\\\/#organization\",\"name\":\"Home of Wool\",\"url\":\"https:\\\/\\\/homeofwool.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/homeofwool.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/homeofwool.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-12-02-at-16.23.20.jpeg\",\"contentUrl\":\"https:\\\/\\\/homeofwool.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-12-02-at-16.23.20.jpeg\",\"width\":700,\"height\":247,\"caption\":\"Home of Wool\"},\"image\":{\"@id\":\"https:\\\/\\\/homeofwool.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/HomeOfWoolOfficial\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coperta pesante in lana \u2013 Copriletto biologico e ipoallergenico | Home of Wool","description":"Resistente e naturale, la coperta in lana pesante offre calore e traspirabilit\u00e0. Ipoallergenica e priva di sostanze tossiche, garantisce un comfort sostenibile per le avventure all'aria aperta, il glamping o le notti accoglienti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homeofwool.com\/it\/negozio\/coperta-termica-nomad\/","og_locale":"it_IT","og_type":"article","og_title":"Heavy Wool Blanket","og_description":"Durable and natural, the Heavy Wool Blanket provides breathable warmth. Hypoallergenic and toxin-free, it ensures sustainable comfort for outdoor adventures, glamping, or cozy nights.","og_url":"https:\/\/homeofwool.com\/it\/negozio\/coperta-termica-nomad\/","og_site_name":"Home of Wool","article_publisher":"https:\/\/facebook.com\/HomeOfWoolOfficial","article_modified_time":"2026-02-09T10:24:44+00:00","og_image":[{"width":1920,"height":1536,"url":"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/home-of-wool-nomad-heavy-wool-blanket-mainn.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/homeofwool.com\/shop\/nomad-heat-blanket\/","url":"https:\/\/homeofwool.com\/shop\/nomad-heat-blanket\/","name":"Coperta pesante in lana \u2013 Copriletto biologico e ipoallergenico | Home of Wool","isPartOf":{"@id":"https:\/\/homeofwool.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/homeofwool.com\/shop\/nomad-heat-blanket\/#primaryimage"},"image":{"@id":"https:\/\/homeofwool.com\/shop\/nomad-heat-blanket\/#primaryimage"},"thumbnailUrl":"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/home-of-wool-nomad-heavy-wool-blanket-mainn.jpg","datePublished":"2025-09-02T12:00:50+00:00","dateModified":"2026-02-09T10:24:44+00:00","description":"Resistente e naturale, la coperta in lana pesante offre calore e traspirabilit\u00e0. Ipoallergenica e priva di sostanze tossiche, garantisce un comfort sostenibile per le avventure all'aria aperta, il glamping o le notti accoglienti.","breadcrumb":{"@id":"https:\/\/homeofwool.com\/shop\/nomad-heat-blanket\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/homeofwool.com\/shop\/nomad-heat-blanket\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/homeofwool.com\/shop\/nomad-heat-blanket\/#primaryimage","url":"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/home-of-wool-nomad-heavy-wool-blanket-mainn.jpg","contentUrl":"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/home-of-wool-nomad-heavy-wool-blanket-mainn.jpg","width":1920,"height":1536,"caption":"nomad heat folded heavy wool blanket"},{"@type":"BreadcrumbList","@id":"https:\/\/homeofwool.com\/shop\/nomad-heat-blanket\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/homeofwool.com\/"},{"@type":"ListItem","position":2,"name":"shop","item":"https:\/\/homeofwool.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Heavy Wool Blanket"}]},{"@type":"WebSite","@id":"https:\/\/homeofwool.com\/#website","url":"https:\/\/homeofwool.com\/","name":"Casa della lana","description":"","publisher":{"@id":"https:\/\/homeofwool.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homeofwool.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/homeofwool.com\/#organization","name":"Casa della lana","url":"https:\/\/homeofwool.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/homeofwool.com\/#\/schema\/logo\/image\/","url":"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-12-02-at-16.23.20.jpeg","contentUrl":"https:\/\/homeofwool.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-12-02-at-16.23.20.jpeg","width":700,"height":247,"caption":"Home of Wool"},"image":{"@id":"https:\/\/homeofwool.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/HomeOfWoolOfficial"]}]}},"_links":{"self":[{"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/product\/217499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/comments?post=217499"}],"version-history":[{"count":4,"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/product\/217499\/revisions"}],"predecessor-version":[{"id":228137,"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/product\/217499\/revisions\/228137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/media\/228005"}],"wp:attachment":[{"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/media?parent=217499"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/product_brand?post=217499"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/product_cat?post=217499"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/homeofwool.com\/it\/wp-json\/wp\/v2\/product_tag?post=217499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}